{"id":10098,"date":"2026-04-15T18:47:58","date_gmt":"2026-04-15T18:47:58","guid":{"rendered":"https:\/\/wallitalia.com\/?post_type=product&#038;p=10098"},"modified":"2026-04-15T18:51:52","modified_gmt":"2026-04-15T18:51:52","slug":"carta-da-parati-veils-ii-inkiostro-bianco","status":"publish","type":"product","link":"https:\/\/wallitalia.com\/en\/product\/carta-da-parati-veils-ii-inkiostro-bianco\/","title":{"rendered":"Carta Da Parati Veils II &#8211; Inkiostro Bianco"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>I rotoli hanno una lunghezza di 100 cm<\/p>\n<p data-start=\"75\" data-end=\"98\"><strong data-start=\"75\" data-end=\"98\">Specifiche Prodotto<\/strong><\/p>\n<ul data-start=\"100\" data-end=\"309\">\n<li data-start=\"100\" data-end=\"132\">\n<p data-start=\"102\" data-end=\"132\">Lunghezza rotolo: <strong data-start=\"120\" data-end=\"130\">100 cm<\/strong><\/p>\n<\/li>\n<li data-start=\"133\" data-end=\"186\">\n<p data-start=\"135\" data-end=\"186\">Versione: <strong data-start=\"145\" data-end=\"157\">vinilica<\/strong> (colla inclusa nel prezzo)<\/p>\n<\/li>\n<li data-start=\"187\" data-end=\"309\">\n<p data-start=\"189\" data-end=\"225\">Disponibile su richiesta anche in:<\/p>\n<ul data-start=\"228\" data-end=\"309\">\n<li data-start=\"228\" data-end=\"257\">\n<p data-start=\"230\" data-end=\"257\"><strong data-start=\"230\" data-end=\"237\">Raw<\/strong> \u2013 larghezza 94 cm<\/p>\n<\/li>\n<li data-start=\"260\" data-end=\"309\">\n<p data-start=\"262\" data-end=\"309\"><strong data-start=\"262\" data-end=\"289\">EQ\u2022dekor fibra di vetro<\/strong> \u2013 larghezza 94 cm (Ideale per ambienti umidi\/bagno)<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p data-start=\"311\" data-end=\"441\"><strong data-start=\"311\" data-end=\"320\">Nota:<\/strong> si consiglia di aggiungere <strong data-start=\"348\" data-end=\"368\">10 cm in altezza<\/strong> rispetto alla misura reale della parete per garantire una corretta posa.<\/p>\n","protected":false},"featured_media":10104,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[37],"product_cat":[245,163,337],"product_tag":[],"class_list":{"0":"post-10098","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-inkiostro-bianco","7":"product_cat-moderne","8":"product_cat-monocromatico","9":"product_cat-studio-zero","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carta Da Parati Veils II - Inkiostro Bianco - Wallitalia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wallitalia.com\/en\/product\/carta-da-parati-veils-ii-inkiostro-bianco\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta Da Parati Veils II - Inkiostro Bianco - Wallitalia\" \/>\n<meta property=\"og:description\" content=\"I rotoli hanno una lunghezza di 100 cm Specifiche Prodotto     Lunghezza rotolo: 100 cm    Versione: vinilica (colla inclusa nel prezzo)    Disponibile su richiesta anche in:     Raw \u2013 larghezza 94 cm    EQ\u2022dekor fibra di vetro \u2013 larghezza 94 cm (Ideale per ambienti umidi\/bagno)     Nota: si consiglia di aggiungere 10 cm in altezza rispetto alla misura reale della parete per garantire una corretta posa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wallitalia.com\/en\/product\/carta-da-parati-veils-ii-inkiostro-bianco\/\" \/>\n<meta property=\"og:site_name\" content=\"Wallitalia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T18:51:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/04\/VEILS-II_INKBNFK1603_AMB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/carta-da-parati-veils-ii-inkiostro-bianco\\\/\",\"url\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/carta-da-parati-veils-ii-inkiostro-bianco\\\/\",\"name\":\"Carta Da Parati Veils II - Inkiostro Bianco - Wallitalia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/carta-da-parati-veils-ii-inkiostro-bianco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/carta-da-parati-veils-ii-inkiostro-bianco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/VEILS-II_INKBNFK1603_AMB.jpg\",\"datePublished\":\"2026-04-15T18:47:58+00:00\",\"dateModified\":\"2026-04-15T18:51:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/carta-da-parati-veils-ii-inkiostro-bianco\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/carta-da-parati-veils-ii-inkiostro-bianco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/carta-da-parati-veils-ii-inkiostro-bianco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/VEILS-II_INKBNFK1603_AMB.jpg\",\"contentUrl\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/VEILS-II_INKBNFK1603_AMB.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/carta-da-parati-veils-ii-inkiostro-bianco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All Products\",\"item\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/all-products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carta Da Parati Veils II &#8211; Inkiostro Bianco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/\",\"name\":\"Wallitalia\",\"description\":\"Customize Wallpaper\",\"publisher\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/#\\\/schema\\\/person\\\/e6e9b664d62ec2d659726c12dfd4195f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/#\\\/schema\\\/person\\\/e6e9b664d62ec2d659726c12dfd4195f\",\"name\":\"Calogero Aurelio Pio Coniglio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png\",\"url\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png\",\"contentUrl\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png\",\"width\":1560,\"height\":522,\"caption\":\"Calogero Aurelio Pio Coniglio\"},\"logo\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png\"},\"sameAs\":[\"https:\\\/\\\/wallitalia.com\\\/\",\"https:\\\/\\\/www.instagram.com\\\/wall_italia\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/wallitaliashop\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta Da Parati Veils II - Inkiostro Bianco - Wallitalia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wallitalia.com\/en\/product\/carta-da-parati-veils-ii-inkiostro-bianco\/","og_locale":"en_US","og_type":"article","og_title":"Carta Da Parati Veils II - Inkiostro Bianco - Wallitalia","og_description":"I rotoli hanno una lunghezza di 100 cm Specifiche Prodotto     Lunghezza rotolo: 100 cm    Versione: vinilica (colla inclusa nel prezzo)    Disponibile su richiesta anche in:     Raw \u2013 larghezza 94 cm    EQ\u2022dekor fibra di vetro \u2013 larghezza 94 cm (Ideale per ambienti umidi\/bagno)     Nota: si consiglia di aggiungere 10 cm in altezza rispetto alla misura reale della parete per garantire una corretta posa.","og_url":"https:\/\/wallitalia.com\/en\/product\/carta-da-parati-veils-ii-inkiostro-bianco\/","og_site_name":"Wallitalia","article_modified_time":"2026-04-15T18:51:52+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/04\/VEILS-II_INKBNFK1603_AMB.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wallitalia.com\/en\/product\/carta-da-parati-veils-ii-inkiostro-bianco\/","url":"https:\/\/wallitalia.com\/en\/product\/carta-da-parati-veils-ii-inkiostro-bianco\/","name":"Carta Da Parati Veils II - Inkiostro Bianco - Wallitalia","isPartOf":{"@id":"https:\/\/wallitalia.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wallitalia.com\/en\/product\/carta-da-parati-veils-ii-inkiostro-bianco\/#primaryimage"},"image":{"@id":"https:\/\/wallitalia.com\/en\/product\/carta-da-parati-veils-ii-inkiostro-bianco\/#primaryimage"},"thumbnailUrl":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/04\/VEILS-II_INKBNFK1603_AMB.jpg","datePublished":"2026-04-15T18:47:58+00:00","dateModified":"2026-04-15T18:51:52+00:00","breadcrumb":{"@id":"https:\/\/wallitalia.com\/en\/product\/carta-da-parati-veils-ii-inkiostro-bianco\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wallitalia.com\/en\/product\/carta-da-parati-veils-ii-inkiostro-bianco\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wallitalia.com\/en\/product\/carta-da-parati-veils-ii-inkiostro-bianco\/#primaryimage","url":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/04\/VEILS-II_INKBNFK1603_AMB.jpg","contentUrl":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/04\/VEILS-II_INKBNFK1603_AMB.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/wallitalia.com\/en\/product\/carta-da-parati-veils-ii-inkiostro-bianco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wallitalia.com\/en\/"},{"@type":"ListItem","position":2,"name":"All Products","item":"https:\/\/wallitalia.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Carta Da Parati Veils II &#8211; Inkiostro Bianco"}]},{"@type":"WebSite","@id":"https:\/\/wallitalia.com\/en\/#website","url":"https:\/\/wallitalia.com\/en\/","name":"Wallitalia","description":"Customize Wallpaper","publisher":{"@id":"https:\/\/wallitalia.com\/en\/#\/schema\/person\/e6e9b664d62ec2d659726c12dfd4195f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wallitalia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/wallitalia.com\/en\/#\/schema\/person\/e6e9b664d62ec2d659726c12dfd4195f","name":"Calogero Aurelio Pio Coniglio","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/01\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png","url":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/01\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png","contentUrl":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/01\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png","width":1560,"height":522,"caption":"Calogero Aurelio Pio Coniglio"},"logo":{"@id":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/01\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png"},"sameAs":["https:\/\/wallitalia.com\/","https:\/\/www.instagram.com\/wall_italia\/","https:\/\/it.pinterest.com\/wallitaliashop\/"]}]}},"_links":{"self":[{"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product\/10098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/comments?post=10098"}],"version-history":[{"count":0,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product\/10098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/media\/10104"}],"wp:attachment":[{"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/media?parent=10098"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product_brand?post=10098"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product_cat?post=10098"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product_tag?post=10098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}