{"id":14204,"date":"2026-04-23T14:38:02","date_gmt":"2026-04-23T14:38:02","guid":{"rendered":"https:\/\/wallitalia.com\/prodotto\/oriente-wallpaper-inkiostro-bianco\/"},"modified":"2026-05-07T18:16:25","modified_gmt":"2026-05-07T18:16:25","slug":"oriente-wallpaper-inkiostro-bianco","status":"publish","type":"product","link":"https:\/\/wallitalia.com\/en\/product\/oriente-wallpaper-inkiostro-bianco\/","title":{"rendered":"Oriente Wallpaper &#8211; Inkiostro Bianco"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The rolls have a length of 68 cm<\/p>\n<p data-start=\"75\" data-end=\"98\"><strong data-start=\"75\" data-end=\"98\">Product Specifications<\/strong><\/p>\n<ul data-start=\"100\" data-end=\"309\">\n<li data-start=\"100\" data-end=\"132\">\n<p data-start=\"102\" data-end=\"132\">Roll length: <strong data-start=\"120\" data-end=\"130\">68 cm<\/strong><\/p>\n<\/li>\n<li data-start=\"133\" data-end=\"186\">\n<p data-start=\"135\" data-end=\"186\">Version: <strong data-start=\"145\" data-end=\"157\">Gold Vinyl<\/strong> (adhesive included in the price)<\/p>\n<\/li>\n<li data-start=\"187\" data-end=\"309\">\n<p data-start=\"189\" data-end=\"225\">The following versions are also available upon request for a quote:<\/p>\n<ul data-start=\"228\" data-end=\"309\">\n<li data-start=\"228\" data-end=\"257\">\n<p data-start=\"230\" data-end=\"257\"><strong data-start=\"230\" data-end=\"237\">Gold Leaf<\/strong> \u2013 width 47 cm<\/p>\n<\/li>\n<li data-start=\"260\" data-end=\"309\">\n<p data-start=\"262\" data-end=\"309\"><strong data-start=\"262\" data-end=\"289\">Pink Gold<\/strong> \u2013 width 47 cm<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p data-start=\"311\" data-end=\"441\"><strong data-start=\"311\" data-end=\"320\">Note:<\/strong> we recommend adding <strong data-start=\"348\" data-end=\"368\">10 cm in height<\/strong> to the actual wall measurement to ensure correct installation.<\/p>\n","protected":false},"featured_media":14208,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[569],"product_cat":[408,409,413,482],"product_tag":[],"class_list":{"0":"post-14204","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-inkiostro-bianco","7":"product_cat-classic","8":"product_cat-eclectic","9":"product_cat-floral","10":"product_cat-studio-zero","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oriente Wallpaper - Inkiostro Bianco - Wallitalia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wallitalia.com\/en\/product\/oriente-wallpaper-inkiostro-bianco\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oriente Wallpaper - Inkiostro Bianco - Wallitalia\" \/>\n<meta property=\"og:description\" content=\"The rolls have a length of 68 cm Product Specifications   Roll length: 68 cm   Version: Gold Vinyl (adhesive included in the price)   The following versions are also available upon request for a quote:   Gold Leaf \u2013 width 47 cm   Pink Gold \u2013 width 47 cm   Note: we recommend adding 10 cm in height to the actual wall measurement to ensure correct installation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wallitalia.com\/en\/product\/oriente-wallpaper-inkiostro-bianco\/\" \/>\n<meta property=\"og:site_name\" content=\"Wallitalia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T18:16:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/04\/ORIENTE_INKQWMG2002_AMB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/oriente-wallpaper-inkiostro-bianco\\\/\",\"url\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/oriente-wallpaper-inkiostro-bianco\\\/\",\"name\":\"Oriente Wallpaper - Inkiostro Bianco - Wallitalia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/oriente-wallpaper-inkiostro-bianco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/oriente-wallpaper-inkiostro-bianco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ORIENTE_INKQWMG2002_AMB.jpg\",\"datePublished\":\"2026-04-23T14:38:02+00:00\",\"dateModified\":\"2026-05-07T18:16:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/oriente-wallpaper-inkiostro-bianco\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/oriente-wallpaper-inkiostro-bianco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/oriente-wallpaper-inkiostro-bianco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ORIENTE_INKQWMG2002_AMB.jpg\",\"contentUrl\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ORIENTE_INKQWMG2002_AMB.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/oriente-wallpaper-inkiostro-bianco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All Products\",\"item\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/all-products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oriente Wallpaper &#8211; Inkiostro Bianco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/\",\"name\":\"Wallitalia\",\"description\":\"Customize Wallpaper\",\"publisher\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/#\\\/schema\\\/person\\\/e6e9b664d62ec2d659726c12dfd4195f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/#\\\/schema\\\/person\\\/e6e9b664d62ec2d659726c12dfd4195f\",\"name\":\"Calogero Aurelio Pio Coniglio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png\",\"url\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png\",\"contentUrl\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png\",\"width\":1560,\"height\":522,\"caption\":\"Calogero Aurelio Pio Coniglio\"},\"logo\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png\"},\"sameAs\":[\"https:\\\/\\\/wallitalia.com\\\/\",\"https:\\\/\\\/www.instagram.com\\\/wall_italia\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/wallitaliashop\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oriente Wallpaper - Inkiostro Bianco - Wallitalia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wallitalia.com\/en\/product\/oriente-wallpaper-inkiostro-bianco\/","og_locale":"en_US","og_type":"article","og_title":"Oriente Wallpaper - Inkiostro Bianco - Wallitalia","og_description":"The rolls have a length of 68 cm Product Specifications   Roll length: 68 cm   Version: Gold Vinyl (adhesive included in the price)   The following versions are also available upon request for a quote:   Gold Leaf \u2013 width 47 cm   Pink Gold \u2013 width 47 cm   Note: we recommend adding 10 cm in height to the actual wall measurement to ensure correct installation.","og_url":"https:\/\/wallitalia.com\/en\/product\/oriente-wallpaper-inkiostro-bianco\/","og_site_name":"Wallitalia","article_modified_time":"2026-05-07T18:16:25+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/04\/ORIENTE_INKQWMG2002_AMB.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wallitalia.com\/en\/product\/oriente-wallpaper-inkiostro-bianco\/","url":"https:\/\/wallitalia.com\/en\/product\/oriente-wallpaper-inkiostro-bianco\/","name":"Oriente Wallpaper - Inkiostro Bianco - Wallitalia","isPartOf":{"@id":"https:\/\/wallitalia.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wallitalia.com\/en\/product\/oriente-wallpaper-inkiostro-bianco\/#primaryimage"},"image":{"@id":"https:\/\/wallitalia.com\/en\/product\/oriente-wallpaper-inkiostro-bianco\/#primaryimage"},"thumbnailUrl":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/04\/ORIENTE_INKQWMG2002_AMB.jpg","datePublished":"2026-04-23T14:38:02+00:00","dateModified":"2026-05-07T18:16:25+00:00","breadcrumb":{"@id":"https:\/\/wallitalia.com\/en\/product\/oriente-wallpaper-inkiostro-bianco\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wallitalia.com\/en\/product\/oriente-wallpaper-inkiostro-bianco\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wallitalia.com\/en\/product\/oriente-wallpaper-inkiostro-bianco\/#primaryimage","url":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/04\/ORIENTE_INKQWMG2002_AMB.jpg","contentUrl":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/04\/ORIENTE_INKQWMG2002_AMB.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/wallitalia.com\/en\/product\/oriente-wallpaper-inkiostro-bianco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wallitalia.com\/en\/"},{"@type":"ListItem","position":2,"name":"All Products","item":"https:\/\/wallitalia.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Oriente Wallpaper &#8211; Inkiostro Bianco"}]},{"@type":"WebSite","@id":"https:\/\/wallitalia.com\/en\/#website","url":"https:\/\/wallitalia.com\/en\/","name":"Wallitalia","description":"Customize Wallpaper","publisher":{"@id":"https:\/\/wallitalia.com\/en\/#\/schema\/person\/e6e9b664d62ec2d659726c12dfd4195f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wallitalia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/wallitalia.com\/en\/#\/schema\/person\/e6e9b664d62ec2d659726c12dfd4195f","name":"Calogero Aurelio Pio Coniglio","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/01\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png","url":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/01\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png","contentUrl":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/01\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png","width":1560,"height":522,"caption":"Calogero Aurelio Pio Coniglio"},"logo":{"@id":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/01\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png"},"sameAs":["https:\/\/wallitalia.com\/","https:\/\/www.instagram.com\/wall_italia\/","https:\/\/it.pinterest.com\/wallitaliashop\/"]}]}},"_links":{"self":[{"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product\/14204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/comments?post=14204"}],"version-history":[{"count":0,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product\/14204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/media\/14208"}],"wp:attachment":[{"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/media?parent=14204"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product_brand?post=14204"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product_cat?post=14204"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product_tag?post=14204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}