{"id":18495,"date":"2026-05-12T08:16:28","date_gmt":"2026-05-12T08:16:28","guid":{"rendered":"https:\/\/wallitalia.com\/?post_type=product&#038;p=18495"},"modified":"2026-05-12T08:19:39","modified_gmt":"2026-05-12T08:19:39","slug":"matildica-wallpaper-inkiostro-bianco-copia","status":"publish","type":"product","link":"https:\/\/wallitalia.com\/en\/product\/matildica-wallpaper-inkiostro-bianco-copia\/","title":{"rendered":"Este Wallpaper &#8211; Inkiostro Bianco"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Rolls have a width of 100 cm<\/p>\n<p data-start=\"75\" data-end=\"98\"><strong data-start=\"75\" data-end=\"98\">Product Specifications<\/strong><\/p>\n<ul data-start=\"100\" data-end=\"309\">\n<li data-start=\"100\" data-end=\"132\">\n<p data-start=\"102\" data-end=\"132\">Roll width: <strong data-start=\"120\" data-end=\"130\">100 cm<\/strong><\/p>\n<\/li>\n<li data-start=\"133\" data-end=\"186\">\n<p data-start=\"135\" data-end=\"186\">Version: <strong data-start=\"145\" data-end=\"157\">vinyl<\/strong> (adhesive included in the price)<\/p>\n<\/li>\n<li data-start=\"187\" data-end=\"309\">\n<p data-start=\"189\" data-end=\"225\">Also available on request in:<\/p>\n<ul data-start=\"228\" data-end=\"309\">\n<li data-start=\"228\" data-end=\"257\">\n<p data-start=\"230\" data-end=\"257\"><strong data-start=\"230\" data-end=\"237\">Raw<\/strong> \u2013 width 94 cm<\/p>\n<\/li>\n<li data-start=\"260\" data-end=\"309\">\n<p data-start=\"262\" data-end=\"309\"><strong data-start=\"262\" data-end=\"289\">EQ\u2022dekor fiberglass<\/strong> \u2013 width 94 cm (Ideal for damp environments\/bathrooms)<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p data-start=\"311\" data-end=\"441\"><strong data-start=\"311\" data-end=\"320\">Note:<\/strong> we recommend adding <strong data-start=\"348\" data-end=\"368\">10 cm in height<\/strong> to the actual wall measurement to ensure correct installation.<\/p>\n","protected":false},"featured_media":18499,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[569],"product_cat":[408,418,428,579,425,441],"product_tag":[],"class_list":{"0":"post-18495","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-inkiostro-bianco","7":"product_cat-classic","8":"product_cat-illustration","9":"product_cat-monochromatic","10":"product_cat-ovre-design","11":"product_cat-textural","12":"product_cat-vintage","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Este Wallpaper - Inkiostro Bianco - Wallitalia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wallitalia.com\/en\/product\/matildica-wallpaper-inkiostro-bianco-copia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Este Wallpaper - Inkiostro Bianco - Wallitalia\" \/>\n<meta property=\"og:description\" content=\"Rolls have a width of 100 cm Product Specifications   Roll width: 100 cm   Version: vinyl (adhesive included in the price)   Also available on request in:   Raw \u2013 width 94 cm   EQ\u2022dekor fiberglass \u2013 width 94 cm (Ideal for damp environments\/bathrooms)   Note: we recommend adding 10 cm in height to the actual wall measurement to ensure correct installation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wallitalia.com\/en\/product\/matildica-wallpaper-inkiostro-bianco-copia\/\" \/>\n<meta property=\"og:site_name\" content=\"Wallitalia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T08:19:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/05\/ESTE_INKIESV2101_11000x1000_AMB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/matildica-wallpaper-inkiostro-bianco-copia\\\/\",\"url\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/matildica-wallpaper-inkiostro-bianco-copia\\\/\",\"name\":\"Este Wallpaper - Inkiostro Bianco - Wallitalia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/matildica-wallpaper-inkiostro-bianco-copia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/matildica-wallpaper-inkiostro-bianco-copia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ESTE_INKIESV2101_11000x1000_AMB.jpg\",\"datePublished\":\"2026-05-12T08:16:28+00:00\",\"dateModified\":\"2026-05-12T08:19:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/matildica-wallpaper-inkiostro-bianco-copia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/matildica-wallpaper-inkiostro-bianco-copia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/matildica-wallpaper-inkiostro-bianco-copia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ESTE_INKIESV2101_11000x1000_AMB.jpg\",\"contentUrl\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ESTE_INKIESV2101_11000x1000_AMB.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/product\\\/matildica-wallpaper-inkiostro-bianco-copia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All Products\",\"item\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/all-products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Este Wallpaper &#8211; Inkiostro Bianco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/\",\"name\":\"Wallitalia\",\"description\":\"Customize Wallpaper\",\"publisher\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/#\\\/schema\\\/person\\\/e6e9b664d62ec2d659726c12dfd4195f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wallitalia.com\\\/en\\\/#\\\/schema\\\/person\\\/e6e9b664d62ec2d659726c12dfd4195f\",\"name\":\"Calogero Aurelio Pio Coniglio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png\",\"url\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png\",\"contentUrl\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png\",\"width\":1560,\"height\":522,\"caption\":\"Calogero Aurelio Pio Coniglio\"},\"logo\":{\"@id\":\"https:\\\/\\\/wallitalia.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png\"},\"sameAs\":[\"https:\\\/\\\/wallitalia.com\\\/\",\"https:\\\/\\\/www.instagram.com\\\/wall_italia\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/wallitaliashop\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Este Wallpaper - Inkiostro Bianco - Wallitalia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wallitalia.com\/en\/product\/matildica-wallpaper-inkiostro-bianco-copia\/","og_locale":"en_US","og_type":"article","og_title":"Este Wallpaper - Inkiostro Bianco - Wallitalia","og_description":"Rolls have a width of 100 cm Product Specifications   Roll width: 100 cm   Version: vinyl (adhesive included in the price)   Also available on request in:   Raw \u2013 width 94 cm   EQ\u2022dekor fiberglass \u2013 width 94 cm (Ideal for damp environments\/bathrooms)   Note: we recommend adding 10 cm in height to the actual wall measurement to ensure correct installation.","og_url":"https:\/\/wallitalia.com\/en\/product\/matildica-wallpaper-inkiostro-bianco-copia\/","og_site_name":"Wallitalia","article_modified_time":"2026-05-12T08:19:39+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/05\/ESTE_INKIESV2101_11000x1000_AMB.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wallitalia.com\/en\/product\/matildica-wallpaper-inkiostro-bianco-copia\/","url":"https:\/\/wallitalia.com\/en\/product\/matildica-wallpaper-inkiostro-bianco-copia\/","name":"Este Wallpaper - Inkiostro Bianco - Wallitalia","isPartOf":{"@id":"https:\/\/wallitalia.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wallitalia.com\/en\/product\/matildica-wallpaper-inkiostro-bianco-copia\/#primaryimage"},"image":{"@id":"https:\/\/wallitalia.com\/en\/product\/matildica-wallpaper-inkiostro-bianco-copia\/#primaryimage"},"thumbnailUrl":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/05\/ESTE_INKIESV2101_11000x1000_AMB.jpg","datePublished":"2026-05-12T08:16:28+00:00","dateModified":"2026-05-12T08:19:39+00:00","breadcrumb":{"@id":"https:\/\/wallitalia.com\/en\/product\/matildica-wallpaper-inkiostro-bianco-copia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wallitalia.com\/en\/product\/matildica-wallpaper-inkiostro-bianco-copia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wallitalia.com\/en\/product\/matildica-wallpaper-inkiostro-bianco-copia\/#primaryimage","url":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/05\/ESTE_INKIESV2101_11000x1000_AMB.jpg","contentUrl":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/05\/ESTE_INKIESV2101_11000x1000_AMB.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/wallitalia.com\/en\/product\/matildica-wallpaper-inkiostro-bianco-copia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wallitalia.com\/en\/"},{"@type":"ListItem","position":2,"name":"All Products","item":"https:\/\/wallitalia.com\/en\/all-products\/"},{"@type":"ListItem","position":3,"name":"Este Wallpaper &#8211; Inkiostro Bianco"}]},{"@type":"WebSite","@id":"https:\/\/wallitalia.com\/en\/#website","url":"https:\/\/wallitalia.com\/en\/","name":"Wallitalia","description":"Customize Wallpaper","publisher":{"@id":"https:\/\/wallitalia.com\/en\/#\/schema\/person\/e6e9b664d62ec2d659726c12dfd4195f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wallitalia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/wallitalia.com\/en\/#\/schema\/person\/e6e9b664d62ec2d659726c12dfd4195f","name":"Calogero Aurelio Pio Coniglio","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/01\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png","url":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/01\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png","contentUrl":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/01\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png","width":1560,"height":522,"caption":"Calogero Aurelio Pio Coniglio"},"logo":{"@id":"https:\/\/wallitalia.com\/wp-content\/uploads\/2026\/01\/cropped-WALLITALIA-Logo-with-Contemporary-Blue-and-Gray-Scheme.png"},"sameAs":["https:\/\/wallitalia.com\/","https:\/\/www.instagram.com\/wall_italia\/","https:\/\/it.pinterest.com\/wallitaliashop\/"]}]}},"_links":{"self":[{"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product\/18495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/comments?post=18495"}],"version-history":[{"count":0,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product\/18495\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/media\/18499"}],"wp:attachment":[{"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/media?parent=18495"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product_brand?post=18495"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product_cat?post=18495"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wallitalia.com\/en\/wp-json\/wp\/v2\/product_tag?post=18495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}